{"id":1675,"date":"2023-04-20T13:30:34","date_gmt":"2023-04-20T11:30:34","guid":{"rendered":"https:\/\/www.lefruitierdeshalles.fr\/?post_type=cpt_services&#038;p=1675"},"modified":"2023-04-27T17:00:19","modified_gmt":"2023-04-27T15:00:19","slug":"courges","status":"publish","type":"cpt_services","link":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/","title":{"rendered":"Courges"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1479921547216{margin-top: -0.8em !important;margin-bottom: 1em !important;}&#8221;]<div id=\"sc_title_1997676934\"\r\n\t\tclass=\"sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Courges<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">Bienvenue dans notre s\u00e9lection de courges, une gamme de l\u00e9gumes polyvalents, d\u00e9licieux et nutritifs qui ajoutera de la couleur et de la vari\u00e9t\u00e9 \u00e0 vos plats. ue vous soyez \u00e0 la recherche de courges d'\u00e9t\u00e9 pour vos salades, ou de courges d'hiver pour vos plats mijot\u00e9s et vos soupes, nous avons tout ce dont vous avez besoin. Notre gamme comprend une vari\u00e9t\u00e9 de courges, y compris les classiques comme la courge butternut et la courge musqu\u00e9e, ainsi que des vari\u00e9t\u00e9s moins connues comme la courge spaghetti et la courge patidou. D\u00e9couvrez d\u00e8s maintenant notre s\u00e9lection de courges fra\u00eeches et savoureuses, riches en nutriments, en fibres et en saveurs, et laissez-vous inspirer pour cr\u00e9er des plats d\u00e9licieux et sains \u00e0 tout moment de l'ann\u00e9e.<\/div><\/div><!-- \/.sc_title -->[vc_empty_space height=&#8221;7.3rem&#8221; alter_height=&#8221;none&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1479883614224{margin-top: -3.6em !important;}&#8221;]<div class=\"sc_item_button sc_button_wrap sc_align_center\"><a href=\"https:\/\/www.ollca.com\/rouen\/boutiques\/fruitierdeshalles\"\r\n\t id=\"sc_button_792556997\" \r\n\tclass=\"sc_button sc_button_default sc_button_size_normal sc_button_icon_left\"\r\n\t\t><span class=\"sc_button_text\"><span class=\"sc_button_title\">Commander<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1676&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_792773821\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Buttercup<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">Buttercup est une vari\u00e9t\u00e9 de courge d'hiver, \u00e9galement connue sous le nom de courge doubeurre. Elle a une forme ronde et l\u00e9g\u00e8rement aplatie avec une peau dure et vert fonc\u00e9. Sa chair est de couleur orange fonc\u00e9 et a une texture dense et l\u00e9g\u00e8rement farineuse. Elle a un go\u00fbt doux et l\u00e9g\u00e8rement sucr\u00e9, avec des notes de noix et de beurre. La courge Buttercup est riche en vitamines A et C, en potassium et en fibres. Elle peut \u00eatre cuite au four, r\u00f4tie ou bouillie, et est souvent utilis\u00e9e dans les soupes et les plats d'accompagnement.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1677&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_290900748\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Butternut BIO<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">La courge butternut bio est une vari\u00e9t\u00e9 de courge musqu\u00e9e de forme allong\u00e9e avec une peau beige clair et une chair orange fonc\u00e9. Elle est cultiv\u00e9e sans l'utilisation de produits chimiques synth\u00e9tiques ni d'OGM, et est donc consid\u00e9r\u00e9e comme \u00e9tant bio. La butternut bio est riche en nutriments tels que les vitamines A, C et E, ainsi que des min\u00e9raux tels que le potassium et le magn\u00e9sium. Elle peut \u00eatre pr\u00e9par\u00e9e de diverses fa\u00e7ons, telles que r\u00f4tie, grill\u00e9e, en pur\u00e9e ou en soupe.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1679&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_1159706057\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Citrouille<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">La citrouille est un l\u00e9gume d'hiver, souvent utilis\u00e9 dans les plats sal\u00e9s et sucr\u00e9s, tels que les soupes, les rago\u00fbts, les gratins, les tartes, les pains et les g\u00e2teaux. Elle est riche en vitamines A et C, ainsi qu'en potassium, et est \u00e9galement une bonne source de fibres. La citrouille peut \u00eatre cuite de nombreuses mani\u00e8res, notamment r\u00f4tie, grill\u00e9e, bouillie, saut\u00e9e et cuite \u00e0 la vapeur.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1680&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_26732587\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Courge de Siam<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">La courge de Siam, \u00e9galement appel\u00e9e courge longue de Chine ou courge de serpent, est une vari\u00e9t\u00e9 de courge d'origine asiatique. Elle mesure g\u00e9n\u00e9ralement de 30 \u00e0 60 cm de long, et sa peau est de couleur vert fonc\u00e9 \u00e0 marron. Sa chair est blanche, ferme et peu fibreuse, avec une saveur douce et l\u00e9g\u00e8rement sucr\u00e9e. La courge de Siam est souvent utilis\u00e9e dans la cuisine asiatique pour pr\u00e9parer des soupes, des saut\u00e9s, des currys et des plats mijot\u00e9s. Elle peut \u00e9galement \u00eatre cuite au four ou grill\u00e9e.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1681&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_1421158352\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Courge Patidou<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">La courge Patidou est une vari\u00e9t\u00e9 de courge de petite taille et de forme ronde, souvent appel\u00e9e \"courge bonnet d'\u00e9v\u00eaque\". Sa peau est vert fonc\u00e9, avec des rayures vert clair ou beige. Sa chair est de couleur jaune-orang\u00e9 et a une texture fine et sucr\u00e9e. Elle est souvent utilis\u00e9e pour les soupes, les gratins, les pur\u00e9es ou les plats de l\u00e9gumes r\u00f4tis. Sa petite taille en fait \u00e9galement une option pratique pour les plats individuels ou les portions de taille moyenne.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1682&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_550200941\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Courge spaghetti<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">La courge spaghetti, \u00e9galement connue sous le nom de spaghetti v\u00e9g\u00e9tal, est une vari\u00e9t\u00e9 de courge d'hiver qui peut \u00eatre utilis\u00e9e comme alternative aux p\u00e2tes. Elle doit son nom \u00e0 la texture filamenteuse de sa chair cuite, qui ressemble \u00e0 des spaghettis. Elle est riche en fibres, en vitamines et en min\u00e9raux, et elle peut \u00eatre pr\u00e9par\u00e9e de nombreuses fa\u00e7ons diff\u00e9rentes, notamment en la faisant cuire au four, \u00e0 la vapeur ou \u00e0 la po\u00eale.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1683&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_1325990045\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Courgette ronde<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">La courgette ronde est une vari\u00e9t\u00e9 de courgette qui pr\u00e9sente une forme sph\u00e9rique. Elle est \u00e9galement appel\u00e9e \"courgette de Nice\" ou \"ronde de Nice\". Cette vari\u00e9t\u00e9 est plus douce et plus juteuse que la courgette classique, avec une texture plus tendre et moins de graines. Elle est souvent utilis\u00e9e pour faire des plats farcis ou pour ajouter de la saveur et de la texture aux salades et aux plats d'accompagnement. La courgette ronde peut \u00eatre cuisin\u00e9e de nombreuses fa\u00e7ons, notamment grill\u00e9e, saut\u00e9e, r\u00f4tie ou farcie.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1684&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_152142772\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Courgettes blanches<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">Les courgettes blanches sont une vari\u00e9t\u00e9 de courgettes qui ont une peau blanche et une chair tendre et d\u00e9licate. Elles ont un go\u00fbt similaire aux courgettes vertes, mais avec une texture l\u00e9g\u00e8rement diff\u00e9rente. Elles peuvent \u00eatre consomm\u00e9es crues ou cuites et sont utilis\u00e9es dans une vari\u00e9t\u00e9 de plats, notamment les soupes, les rago\u00fbts, les gratins et les saut\u00e9s. Les courgettes blanches sont riches en vitamines et en min\u00e9raux, et sont \u00e9galement une excellente source de fibres alimentaires.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1685&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_974601408\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Courgettes jaunes<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">Courgettes jaunes sont des l\u00e9gumes de la famille des courges, avec une peau lisse et brillante et une chair ferme et croquante. Elles ont une saveur douce et d\u00e9licate, l\u00e9g\u00e8rement sucr\u00e9e et sont souvent utilis\u00e9es dans les plats d'\u00e9t\u00e9, les salades et les plats \u00e0 base de l\u00e9gumes. Comme les autres vari\u00e9t\u00e9s de courgettes, elles sont riches en vitamines et min\u00e9raux, en fibres et en antioxydants.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1686&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_833502990\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Courgettes vertes<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">Les courgettes vertes sont des l\u00e9gumes de la famille des cucurbitac\u00e9es. Elles sont cultiv\u00e9es pour leur fruit allong\u00e9 et cylindrique de couleur vert fonc\u00e9. Les courgettes vertes sont souvent consomm\u00e9es crues ou cuites et sont tr\u00e8s polyvalentes en cuisine. Elles sont riches en fibres, en vitamines (notamment en vitamine C) et en min\u00e9raux (potassium, magn\u00e9sium). Les courgettes vertes peuvent \u00eatre grill\u00e9es, r\u00f4ties, saut\u00e9es, farcies ou m\u00eame utilis\u00e9es dans des soupes ou des smoothies.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1687&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_910550186\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">P\u00e2tisson<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">Le p\u00e2tisson est une vari\u00e9t\u00e9 de courge, \u00e9galement appel\u00e9e \u00ab artichaut d'Espagne \u00bb, en raison de la ressemblance de sa saveur avec celle de l'artichaut. Sa forme particuli\u00e8re, en disque aplati, en fait un l\u00e9gume d\u00e9coratif int\u00e9ressant pour les pr\u00e9sentations culinaires. Il existe des vari\u00e9t\u00e9s de p\u00e2tissons de diff\u00e9rentes couleurs, allant du blanc au vert en passant par le jaune et l'orange. Le p\u00e2tisson peut \u00eatre cuisin\u00e9 de diff\u00e9rentes mani\u00e8res, notamment en gratin, en soupe, ou encore en beignets.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1688&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_1704585439\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Potimarron BIO<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">Le potimarron bio est une vari\u00e9t\u00e9 de courge d'hiver de couleur orange fonc\u00e9, souvent utilis\u00e9e pour la cuisine. Il est issu de l'agriculture biologique, ce qui signifie qu'il est cultiv\u00e9 sans l'utilisation de produits chimiques de synth\u00e8se tels que les pesticides et les engrais chimiques. Le potimarron bio est \u00e9galement cultiv\u00e9 selon des pratiques agricoles durables qui respectent l'environnement et la biodiversit\u00e9. Il est riche en vitamines, min\u00e9raux et antioxydants et peut \u00eatre utilis\u00e9 dans une vari\u00e9t\u00e9 de plats, tels que les soupes, les rago\u00fbts et les pur\u00e9es.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1681907884770{background-color: #f28c02 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][vc_single_image image=&#8221;1689&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_circle_2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;&#8221; alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_1853716109\"\r\n\t\tclass=\"scheme_dark sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_align_default sc_item_title_style_default\">Potiron<\/h3><div class=\"sc_item_descr sc_title_descr sc_align_default\">Le potiron est une vari\u00e9t\u00e9 de courge, \u00e9galement appel\u00e9e courge musqu\u00e9e de Provence. Elle est de forme ronde ou ovale, avec une peau \u00e9paisse de couleur orange. Sa chair est douce, sucr\u00e9e et l\u00e9g\u00e8rement farineuse. Le potiron est souvent utilis\u00e9 pour faire des soupes, des pur\u00e9es ou des gratins. Il est \u00e9galement utilis\u00e9 en p\u00e2tisserie, notamment pour r\u00e9aliser des tartes et des cakes.<\/div><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row][vc_column css=&#8221;.vc_custom_1479889131039{margin-top: 1em !important;margin-bottom: -3.5em !important;}&#8221;]<div id=\"sc_title_1026860146\"\r\n\t\tclass=\"sc_title sc_title_default\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_default\">Nos recettes<\/h6><h3 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default\">Une id\u00e9e de recette ?<\/h3><\/div><!-- \/.sc_title -->[vc_empty_space height=&#8221;2.6rem&#8221; alter_height=&#8221;none&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Bienvenue dans notre s\u00e9lection de courges.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","class_list":["post-1675","cpt_services","type-cpt_services","status-publish","hentry","cpt_services_group-nos-legumes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Courges - Fruitier des Halles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Courges - Fruitier des Halles\" \/>\n<meta property=\"og:description\" content=\"Bienvenue dans notre s\u00e9lection de courges.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/\" \/>\n<meta property=\"og:site_name\" content=\"Fruitier des Halles\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T15:00:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/\",\"url\":\"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/\",\"name\":\"Courges - Fruitier des Halles\",\"isPartOf\":{\"@id\":\"https:\/\/www.lefruitierdeshalles.fr\/#website\"},\"datePublished\":\"2023-04-20T11:30:34+00:00\",\"dateModified\":\"2023-04-27T15:00:19+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lefruitierdeshalles.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Courges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lefruitierdeshalles.fr\/#website\",\"url\":\"https:\/\/www.lefruitierdeshalles.fr\/\",\"name\":\"Fruitier des Halles\",\"description\":\"Primeur \u00e0 Rouen\",\"publisher\":{\"@id\":\"https:\/\/www.lefruitierdeshalles.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lefruitierdeshalles.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lefruitierdeshalles.fr\/#organization\",\"name\":\"Fruitier des Halles\",\"url\":\"https:\/\/www.lefruitierdeshalles.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lefruitierdeshalles.fr\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.lefruitierdeshalles.fr\/wp-content\/uploads\/2023\/04\/cropped-Logo-3_Plan-de-travail-1-03.png\",\"contentUrl\":\"http:\/\/www.lefruitierdeshalles.fr\/wp-content\/uploads\/2023\/04\/cropped-Logo-3_Plan-de-travail-1-03.png\",\"width\":512,\"height\":512,\"caption\":\"Fruitier des Halles\"},\"image\":{\"@id\":\"https:\/\/www.lefruitierdeshalles.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/lefruitierdeshalles_rouen\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Courges - Fruitier des Halles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/","og_locale":"fr_FR","og_type":"article","og_title":"Courges - Fruitier des Halles","og_description":"Bienvenue dans notre s\u00e9lection de courges.","og_url":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/","og_site_name":"Fruitier des Halles","article_modified_time":"2023-04-27T15:00:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/","url":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/","name":"Courges - Fruitier des Halles","isPartOf":{"@id":"https:\/\/www.lefruitierdeshalles.fr\/#website"},"datePublished":"2023-04-20T11:30:34+00:00","dateModified":"2023-04-27T15:00:19+00:00","breadcrumb":{"@id":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/courges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lefruitierdeshalles.fr\/"},{"@type":"ListItem","position":2,"name":"Services","item":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/services\/"},{"@type":"ListItem","position":3,"name":"Courges"}]},{"@type":"WebSite","@id":"https:\/\/www.lefruitierdeshalles.fr\/#website","url":"https:\/\/www.lefruitierdeshalles.fr\/","name":"Fruitier des Halles","description":"Primeur \u00e0 Rouen","publisher":{"@id":"https:\/\/www.lefruitierdeshalles.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lefruitierdeshalles.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lefruitierdeshalles.fr\/#organization","name":"Fruitier des Halles","url":"https:\/\/www.lefruitierdeshalles.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lefruitierdeshalles.fr\/#\/schema\/logo\/image\/","url":"http:\/\/www.lefruitierdeshalles.fr\/wp-content\/uploads\/2023\/04\/cropped-Logo-3_Plan-de-travail-1-03.png","contentUrl":"http:\/\/www.lefruitierdeshalles.fr\/wp-content\/uploads\/2023\/04\/cropped-Logo-3_Plan-de-travail-1-03.png","width":512,"height":512,"caption":"Fruitier des Halles"},"image":{"@id":"https:\/\/www.lefruitierdeshalles.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lefruitierdeshalles_rouen\/"]}]}},"_links":{"self":[{"href":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/wp-json\/wp\/v2\/cpt_services\/1675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/wp-json\/wp\/v2\/cpt_services"}],"about":[{"href":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/wp-json\/wp\/v2\/types\/cpt_services"}],"author":[{"embeddable":true,"href":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"http:\/\/www.lefruitierdeshalles.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}